{"id":16449,"date":"2021-03-24T23:49:05","date_gmt":"2021-03-24T21:49:05","guid":{"rendered":"https:\/\/www.gerberarchitekten.de\/?p=16449"},"modified":"2021-06-08T15:17:29","modified_gmt":"2021-06-08T13:17:29","slug":"city-tower-bo-2-2-2-2-2-3-4","status":"publish","type":"post","link":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/","title":{"rendered":"Groundbreaking ceremony for CALEDO research building at TU Dortmund University"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-1024x768.jpg\" alt=\"\" class=\"wp-image-16453\" srcset=\"https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-1024x768.jpg 1024w, https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-300x225.jpg 300w, https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-768x576.jpg 768w, https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-1536x1152.jpg 1536w, https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-2048x1536.jpg 2048w, https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-219x164.jpg 219w, https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-750x563.jpg 750w, https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-172x129.jpg 172w, https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-360x270.jpg 360w, https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-720x540.jpg 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The ground-breaking ceremony for the new Caledo building took place in compliance with special corona protection measures. The official construction phase was initiated in the presence of representatives of the user and builder sides as well as the Mayor of Dortmund, Thomas Westphal, and the Minister for Culture and Science of the State of North Rhine-Westphalia, Isabel Pfeiffer-Poensgen. A new research building with around 4,000 square metres of floor space and 100 workplaces in state-of-the-art laboratories will now be built on the TU Dortmund campus by the beginning of 2025. In the future, liquid phases will be customised for environmentally friendly and innovative processes in chemistry and biotechnology or for pharmaceutical products in the &#8220;Center for Advanced Liquid-Phase Engineering Dortmund&#8221;, or CALEDO for short. &#8220;With CALEDO, an internationally visible research centre is being created that has a supra-regional significance for research in the field of bio- and chemical engineering,&#8221; says Minister Pfeiffer-Poensgen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interdisciplinary cutting-edge research on the North Campus<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-16449","post","type-post","status-publish","format-standard","hentry","category-allgemein-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Groundbreaking ceremony for CALEDO research building at TU Dortmund University - Gerber Architekten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Groundbreaking ceremony for CALEDO research building at TU Dortmund University - Gerber Architekten\" \/>\n<meta property=\"og:description\" content=\"Interdisciplinary cutting-edge research on the North Campus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Gerber Architekten\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gerberarchitekten\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-24T21:49:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-08T13:17:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-1024x768.jpg\" \/>\n<meta name=\"author\" content=\"sweicherding\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sweicherding\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/\"},\"author\":{\"name\":\"sweicherding\",\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/#\\\/schema\\\/person\\\/11a4f99da45c8b59c52f05244a67720c\"},\"headline\":\"Groundbreaking ceremony for CALEDO research building at TU Dortmund University\",\"datePublished\":\"2021-03-24T21:49:05+00:00\",\"dateModified\":\"2021-06-08T13:17:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/\"},\"wordCount\":159,\"image\":{\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/app\\\/uploads\\\/2021\\\/03\\\/P1060703-1024x768.jpg\",\"articleSection\":[\"Allgemein @en\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/\",\"url\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/\",\"name\":\"Groundbreaking ceremony for CALEDO research building at TU Dortmund University - Gerber Architekten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/app\\\/uploads\\\/2021\\\/03\\\/P1060703-1024x768.jpg\",\"datePublished\":\"2021-03-24T21:49:05+00:00\",\"dateModified\":\"2021-06-08T13:17:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/#\\\/schema\\\/person\\\/11a4f99da45c8b59c52f05244a67720c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/app\\\/uploads\\\/2021\\\/03\\\/P1060703-1024x768.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/app\\\/uploads\\\/2021\\\/03\\\/P1060703-1024x768.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/city-tower-bo-2-2-2-2-2-3-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Groundbreaking ceremony for CALEDO research building at TU Dortmund University\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/#website\",\"url\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/\",\"name\":\"Gerber Architekten\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gerberarchitekten.de\\\/#\\\/schema\\\/person\\\/11a4f99da45c8b59c52f05244a67720c\",\"name\":\"sweicherding\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Groundbreaking ceremony for CALEDO research building at TU Dortmund University - Gerber Architekten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/","og_locale":"en_US","og_type":"article","og_title":"Groundbreaking ceremony for CALEDO research building at TU Dortmund University - Gerber Architekten","og_description":"Interdisciplinary cutting-edge research on the North Campus","og_url":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/","og_site_name":"Gerber Architekten","article_publisher":"https:\/\/www.facebook.com\/gerberarchitekten","article_published_time":"2021-03-24T21:49:05+00:00","article_modified_time":"2021-06-08T13:17:29+00:00","og_image":[{"url":"https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-1024x768.jpg","type":"","width":"","height":""}],"author":"sweicherding","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sweicherding","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/#article","isPartOf":{"@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/"},"author":{"name":"sweicherding","@id":"https:\/\/www.gerberarchitekten.de\/#\/schema\/person\/11a4f99da45c8b59c52f05244a67720c"},"headline":"Groundbreaking ceremony for CALEDO research building at TU Dortmund University","datePublished":"2021-03-24T21:49:05+00:00","dateModified":"2021-06-08T13:17:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/"},"wordCount":159,"image":{"@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-1024x768.jpg","articleSection":["Allgemein @en"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/","url":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/","name":"Groundbreaking ceremony for CALEDO research building at TU Dortmund University - Gerber Architekten","isPartOf":{"@id":"https:\/\/www.gerberarchitekten.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/#primaryimage"},"image":{"@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-1024x768.jpg","datePublished":"2021-03-24T21:49:05+00:00","dateModified":"2021-06-08T13:17:29+00:00","author":{"@id":"https:\/\/www.gerberarchitekten.de\/#\/schema\/person\/11a4f99da45c8b59c52f05244a67720c"},"breadcrumb":{"@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/#primaryimage","url":"https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-1024x768.jpg","contentUrl":"https:\/\/www.gerberarchitekten.de\/app\/uploads\/2021\/03\/P1060703-1024x768.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gerberarchitekten.de\/en\/city-tower-bo-2-2-2-2-2-3-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.gerberarchitekten.de\/en\/"},{"@type":"ListItem","position":2,"name":"Groundbreaking ceremony for CALEDO research building at TU Dortmund University"}]},{"@type":"WebSite","@id":"https:\/\/www.gerberarchitekten.de\/#website","url":"https:\/\/www.gerberarchitekten.de\/","name":"Gerber Architekten","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gerberarchitekten.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.gerberarchitekten.de\/#\/schema\/person\/11a4f99da45c8b59c52f05244a67720c","name":"sweicherding"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/posts\/16449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/comments?post=16449"}],"version-history":[{"count":2,"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/posts\/16449\/revisions"}],"predecessor-version":[{"id":16622,"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/posts\/16449\/revisions\/16622"}],"wp:attachment":[{"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/media?parent=16449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/categories?post=16449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gerberarchitekten.de\/en\/wp-json\/wp\/v2\/tags?post=16449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}